{"id":1464,"count":1,"description":"","link":"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/","name":"sensor R6 III","slug":"sensor-r6-iii","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sensor R6 III archivos - Blog de Carlos Castro Fot\u00f3grafo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sensor R6 III archivos - Blog de Carlos Castro Fot\u00f3grafo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Carlos Castro Fot\u00f3grafo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/tag\\\/sensor-r6-iii\\\/\",\"url\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/tag\\\/sensor-r6-iii\\\/\",\"name\":\"sensor R6 III archivos - Blog de Carlos Castro Fot\u00f3grafo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/tag\\\/sensor-r6-iii\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/tag\\\/sensor-r6-iii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sensor R6 III\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/\",\"name\":\"Blog de Carlos Castro Fot\u00f3grafo\",\"description\":\"Todo sobre Fotograf\u00eda, V\u00eddeo y Tecnolog\u00eda, para apasionados de la imagen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/#\\\/schema\\\/person\\\/f2df3dbaf3422e563228db874428292d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.carloscastrofotografo.com\\\/blog\\\/#\\\/schema\\\/person\\\/f2df3dbaf3422e563228db874428292d\",\"name\":\"Carlos Castro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfdb382b872c007d17784b7cf24288a868cd90f2a34825da78d451a9ddbb4dfe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfdb382b872c007d17784b7cf24288a868cd90f2a34825da78d451a9ddbb4dfe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfdb382b872c007d17784b7cf24288a868cd90f2a34825da78d451a9ddbb4dfe?s=96&d=mm&r=g\",\"caption\":\"Carlos Castro\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfdb382b872c007d17784b7cf24288a868cd90f2a34825da78d451a9ddbb4dfe?s=96&d=mm&r=g\"},\"description\":\"Fot\u00f3grafo, Videografo y apasionado de la tecnolog\u00eda. Cazador de tormentas y astrofot\u00f3grafo amateur.\",\"sameAs\":[\"https:\\\/\\\/www.carloscastrofotografo.com\",\"https:\\\/\\\/www.youtube.com\\\/carloscastrofotografo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sensor R6 III archivos - Blog de Carlos Castro Fot\u00f3grafo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/","og_locale":"es_ES","og_type":"article","og_title":"sensor R6 III archivos - Blog de Carlos Castro Fot\u00f3grafo","og_url":"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/","og_site_name":"Blog de Carlos Castro Fot\u00f3grafo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/","url":"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/","name":"sensor R6 III archivos - Blog de Carlos Castro Fot\u00f3grafo","isPartOf":{"@id":"https:\/\/www.carloscastrofotografo.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carloscastrofotografo.com\/blog\/tag\/sensor-r6-iii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.carloscastrofotografo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"sensor R6 III"}]},{"@type":"WebSite","@id":"https:\/\/www.carloscastrofotografo.com\/blog\/#website","url":"https:\/\/www.carloscastrofotografo.com\/blog\/","name":"Blog de Carlos Castro Fot\u00f3grafo","description":"Todo sobre Fotograf\u00eda, V\u00eddeo y Tecnolog\u00eda, para apasionados de la imagen.","publisher":{"@id":"https:\/\/www.carloscastrofotografo.com\/blog\/#\/schema\/person\/f2df3dbaf3422e563228db874428292d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carloscastrofotografo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/www.carloscastrofotografo.com\/blog\/#\/schema\/person\/f2df3dbaf3422e563228db874428292d","name":"Carlos Castro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dfdb382b872c007d17784b7cf24288a868cd90f2a34825da78d451a9ddbb4dfe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dfdb382b872c007d17784b7cf24288a868cd90f2a34825da78d451a9ddbb4dfe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfdb382b872c007d17784b7cf24288a868cd90f2a34825da78d451a9ddbb4dfe?s=96&d=mm&r=g","caption":"Carlos Castro"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/dfdb382b872c007d17784b7cf24288a868cd90f2a34825da78d451a9ddbb4dfe?s=96&d=mm&r=g"},"description":"Fot\u00f3grafo, Videografo y apasionado de la tecnolog\u00eda. Cazador de tormentas y astrofot\u00f3grafo amateur.","sameAs":["https:\/\/www.carloscastrofotografo.com","https:\/\/www.youtube.com\/carloscastrofotografo"]}]}},"_links":{"self":[{"href":"https:\/\/www.carloscastrofotografo.com\/blog\/wp-json\/wp\/v2\/tags\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carloscastrofotografo.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.carloscastrofotografo.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.carloscastrofotografo.com\/blog\/wp-json\/wp\/v2\/posts?tags=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}